{"id":5203,"date":"2025-08-14T13:43:16","date_gmt":"2025-08-14T13:43:16","guid":{"rendered":"https:\/\/zero-c.com\/privacy-policy\/"},"modified":"2026-03-03T01:01:03","modified_gmt":"2026-03-03T01:01:03","slug":"politique-confidentialite","status":"publish","type":"page","link":"https:\/\/zero-c.com\/fr\/politique-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5203\" class=\"elementor elementor-5203 elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85fb935 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85fb935\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41d865b\" data-id=\"41d865b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-103d2f3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"103d2f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20794241 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20794241\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-58c7bfee\" data-id=\"58c7bfee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bc6b9ae elementor-widget elementor-widget-text-editor\" data-id=\"5bc6b9ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La protection de la vie priv\u00e9e est importante pour Z\u00e9ro-C. Pour cette raison, nous avons mis en place des mesures de protection et des pratiques de saine gestion de vos renseignements personnels conform\u00e9ment aux lois applicables, notamment la Loi 25.<\/p><p>La pr\u00e9sente politique de confidentialit\u00e9 (la \u00ab Politique \u00bb), qui doit \u00eatre lue conjointement avec les conditions d\u2019utilisation du site web, d\u00e9crit nos pratiques en mati\u00e8re de collecte, d\u2019utilisation, de traitement, de communication et de conservation des Renseignements personnels de nos clients, visiteurs et utilisateurs.<\/p><p>En utilisant nos sites web https:\/\/zero-c.com\/ca et https:\/\/zero-c.com\/ca\/fr\/ (le \u00ab Site web \u00bb) ou en transigeant avez nous, vous acceptez que nous puissions recueillir, utiliser, traiter, divulguer et conserver vos Renseignements personnels conform\u00e9ment aux conditions d\u00e9crites aux pr\u00e9sentes. Si vous n\u2019acceptez pas de respecter et d\u2019\u00eatre li\u00e9 par la pr\u00e9sente Politique, vous n\u2019\u00eates pas autoris\u00e9 \u00e0 visiter, acc\u00e9der ou utiliser notre Site web, ni \u00e0 partager vos Renseignements personnels avec nous.<\/p><p>Cette Politique ne s\u2019applique pas aux Renseignements personnels des employ\u00e9s, des repr\u00e9sentants et des consultants de Z\u00e9ro-C, ou \u00e0 toute autre personne affili\u00e9e \u00e0 Z\u00e9ro-C, ainsi qu\u2019\u00e0 toute information qui ne constitue pas un renseignement personnel tel que d\u00e9fini par la loi applicable.<\/p><h3>But de cette Politique<\/h3><p>Cette Politique vous indique quels renseignements personnels nous recueillons par un moyen technologique, comment nous les traitons, et quand nous avons besoin de les communiquer \u00e0 des sous-traitants ou des tiers.<\/p><p>Le terme \u00ab renseignements personnels \u00bb d\u00e9signe toute information qui concerne une personne physique et qui r\u00e9v\u00e8le, de mani\u00e8re directe ou indirecte, quelque chose sur l\u2019identit\u00e9, les caract\u00e9ristiques ou les activit\u00e9s de cette personne. Par exemple, il peut s\u2019agir de votre nom, date de naissance, adresse de courriel personnelle, vos renseignements financiers ou vos num\u00e9ros d\u2019identification personnels.<\/p><h3>Communiquez avec nous<\/h3><p>Toute question, commentaire, demande, pr\u00e9occupation, exercice d\u2019un droit ou d\u00e9p\u00f4t d\u2018une plainte portant sur la pr\u00e9sente Politique de confidentialit\u00e9 doit \u00eatre transmis \u00e0 notre Responsable de la protection des renseignements personnels (RPRP) aux coordonn\u00e9es suivantes :<\/p><p>Courriel :<a href=\"mailto:rprp@zero-c.com\">\u00a0rprp@zero-c.com<\/a><br \/>Adresse : 1061 rue Marie-Victorin<br \/>Saint-Bruno-de-Montarville (Qu\u00e9bec) J3V 0M7, Canada<\/p><h3>Consentement \u00e0 la collecte des renseignements personnels<\/h3><p>Pour Z\u00e9ro-C, le respect de votre priv\u00e9e et de la confidentialit\u00e9 de vos donn\u00e9es est primordial. C\u2018est pourquoi cette politique de confidentialit\u00e9 vous indique quels renseignements nous recueillons par un moyen \u00e9lectronique et \u00e0 quelles fins, les moyens utilis\u00e9s pour la collecte, comment nous les traitons, et quand nous avons besoin de les communiquer \u00e0 des sous-traitants ou des tiers, les mesures de confidentialit\u00e9 et de s\u00e9curit\u00e9 ainsi que vos droits en lien avec vos Renseignements personnels.<\/p><p>En nous fournissant les Renseignements personnels, vous autorisez Z\u00e9ro-C \u00e0 proc\u00e9der \u00e0 la collecte et au traitement de vos renseignements personnels qui sont n\u00e9cessaires pour vous offrir nos produits et services. Sachez que vous demeurez ma\u00eetres en tout temps de vos Renseignements personnels et que vous pouvez refuser que nous collections des Renseignements personnels \u00e0 votre sujet. Pour ce faire, il suffit de nous l\u2019indiquer ou de nous le mentionner lorsque les Renseignements sont collect\u00e9s sur papier, verbalement ou en pr\u00e9sence d\u2019un membre de notre personnel. Il vous est \u00e9galement possible de vous informer aupr\u00e8s de notre Responsable de la protection des renseignements personnels (RPRP) des Renseignements collect\u00e9s par des moyens \u00e9lectroniques et de nous indiquer votre refus \u00e0 la collecte. Il est alors possible que nous ne puissions pas vous servir.<\/p><p>Le consentement que vous nous donnez au moment de la collecte ou du traitement de vos renseignements personnels peut \u00eatre retir\u00e9 en tout temps. Nous nous assurerons de respecter votre choix conform\u00e9ment \u00e0 nos obligations l\u00e9gales.<\/p><p>Dans le cadre de nos activit\u00e9s, nous collectons et utilisons des Renseignements personnels selon des moyens de collecte sp\u00e9cifi\u00e9s tels que :<\/p><p>Lors de navigation sur notre site Web;<br \/>Lors de visites dans nos places d\u2019affaire o\u00f9 des cam\u00e9ras de surveillance en circuit ferm\u00e9 sont utilis\u00e9es;<br \/>Par l\u2019utilisation du Wi-Fi dans nos places d\u2019affaire;<br \/>Lors du t\u00e9l\u00e9chargement de nos applications sur vos appareils \u00e9lectroniques intelligents;<br \/>Lors de nos communications par t\u00e9l\u00e9phone ou par clavardage en direct;<br \/>Lors d\u2019interactions par m\u00e9dias sociaux;<br \/>Lors d\u2019interaction sur des sites Web tels que Facebook, LinkedIn, etc.<br \/>Lors d\u2019interactions avec nos repr\u00e9sentants autoris\u00e9s<\/p><h3>Renseignements personnels recueillis<\/h3><p>Dans le cadre de nos activit\u00e9s, nous pouvons collecter, traiter et utiliser diff\u00e9rents types de renseignements personnels. Nous nous effor\u00e7ons de limiter la collecte des renseignements personnels \u00e0 ceux qui sont n\u00e9cessaires pour vous offrir nos services ou qui sont permis par la loi.<\/p><h4>Les renseignements personnels que nous recueillons incluent :<\/h4><p>Via notre Site web et tous les moyens ou site \u00e9lectronique :<br \/>des coordonn\u00e9es, tels votre nom et pr\u00e9nom, votre adresse courriel et votre num\u00e9ro de t\u00e9l\u00e9phone, pour nous contacter par notre Site web;<br \/>des renseignements, tels que vos coordonn\u00e9es, votre profil LinkedIn et votre CV, lorsque vous postulez pour un emploi aupr\u00e8s de nous;<br \/>des renseignements, tels que vos coordonn\u00e9es et du type de propri\u00e9t\u00e9 que vous d\u00e9tenez, lorsque vous faites une demande de soumission;<br \/>des renseignements recueillis automatiquement lors de l\u2019utilisation du Site incluant des renseignements de connexions et autres informations sur vos activit\u00e9s sur le Site web, comme votre adresse IP, les pages que vous avez consult\u00e9es et les requ\u00eates, l\u2019heure et la date de vos visites, le nombre de connexions, le syst\u00e8me d\u2019exploitation de votre appareil et autres informations mat\u00e9rielles et logicielles;<\/p><h4>Lors de vos interactions avec nous :<\/h4><p>des informations professionnelles ou relatives \u00e0 l\u2019emploi, comme votre curriculum vitae, votre lieu d\u2019emploi, titres ou postes, employeurs, entreprises d\u00e9tenues, salaire ou revenu de travail autonome ainsi que les renseignements \u00e0 l\u2019\u00e9gard de vos ant\u00e9c\u00e9dents criminels et d\u2019autres informations que vous nous fournissez lorsque vous postulez pour un emploi;<br \/>des coordonn\u00e9es, tels votre nom et pr\u00e9nom, votre adresse courriel, votre num\u00e9ro de t\u00e9l\u00e9phone, votre adresse pour la cr\u00e9ation d\u2019un compte client;<br \/>des renseignements relatifs \u00e0 des produits ou services, tels les renseignements concernant les services que nous vous avons rendus;<br \/>des informations relatives aux transactions et au paiement, comme le mode de paiement utilis\u00e9, la date et l\u2019heure, le montant du paiement, le code postal de facturation, votre adresse et d\u2019autres informations connexes;<br \/>des renseignements que vous choisissez de fournir ou de nous transmettre, par exemple, lorsque vous remplissez un formulaire, r\u00e9pondez \u00e0 des sondages ou communiquez avec l\u2019un de nos employ\u00e9s ou repr\u00e9sentants.<\/p><h3>Utilisation des renseignements personnels<\/h3><p>De fa\u00e7on g\u00e9n\u00e9rale, nous utilisons vos renseignements personnels que pour les fins permises ou requises par la loi ou pour les fins suivantes :<br \/>offrir ou am\u00e9liorer nos produits et services ou d\u00e9velopper de nouveaux produits et services;<br \/>r\u00e9pondre \u00e0 vos questions, recueillir des avis et commentaires ou vous fournir une assistance au besoin;<br \/>exploiter, maintenir, superviser, d\u00e9velopper, am\u00e9liorer et offrir toutes les fonctionnalit\u00e9s de notre Site web;<br \/>\u00e0 des fins de v\u00e9rifications de votre identit\u00e9, de vos ant\u00e9c\u00e9dents personnels, comme permis par la loi, ou pour respecter nos obligations en vertu des lois et r\u00e8glements en vigueur;<br \/>envoyer des messages, des mises \u00e0 jour, des alertes de s\u00e9curit\u00e9 ou transmettre des communications conform\u00e9ment \u00e0 la loi;<br \/>administrer un concours, une promotion, un sondage ou une autre fonctionnalit\u00e9 du Site web ou de nos services;<br \/>effectuer des recherches et des analyses en lien avec notre entreprise et nos services;<br \/>d\u00e9tecter et pr\u00e9venir les fraudes, erreurs, pourriels, abus, incidents de s\u00e9curit\u00e9 et autres activit\u00e9s pr\u00e9judiciables;<br \/>constater, exercer ou d\u00e9fendre un droit ou une proc\u00e9dure en justice.<br \/>Nous respectons toujours les buts pour lesquels nous avons recueilli vos renseignements personnels. Si nous souhaitons utiliser ou communiquer vos renseignements personnels pour d\u2019autres buts, nous vous demanderons votre consentement, sauf dans les cas permis par la loi.<\/p><h3>Individus \u00e2g\u00e9s de moins de 14 ans<\/h3><p>Nous ne recueillons et n\u2019utilisons pas sciemment des renseignements personnels de personnes \u00e2g\u00e9es de moins de 14 ans. Si vous avez moins de 14 ans, vous ne devez pas nous fournir vos renseignements personnels sans le consentement de vos parents ou de votre tuteur.<\/p><p>Si vous \u00eates un parent ou un tuteur et que vous apprenez que votre enfant nous a fourni des renseignements personnels sans consentement, veuillez nous contacter comme indiqu\u00e9 \u00e0 la section \u00ab Communiquez avec nous \u00bb pour demander que nous supprimions les renseignements personnels de cet enfant de nos syst\u00e8mes.<\/p><h3>Communication des renseignements personnels<\/h3><p>Dans le cadre de nos activit\u00e9s, nous rendons accessibles vos renseignements personnels \u00e0 nos employ\u00e9s, consultants ou mandataires dont les fonctions l\u2019exigent.<\/p><p>Bien que nous tentions d\u2019\u00e9viter de partager vos renseignements personnels avec des tiers, nous pouvons faire appel \u00e0 des fournisseurs de services pour ex\u00e9cuter divers services pour notre compte. Nous utilisons des fournisseurs pour l\u2019analyse des donn\u00e9es (Google Analytics), la gestion et la s\u00e9curit\u00e9 informatique, la gestion de notre Site web, le marketing, ainsi que l\u2019h\u00e9bergement et le stockage de donn\u00e9es. Dans ces circonstances, nous ne fournissons que les renseignements personnels n\u00e9cessaires \u00e0 l\u2019ex\u00e9cution de leur mandat et nous nous engageons \u00e0 ce que les principes \u00e9nonc\u00e9s dans la pr\u00e9sente Politique soient respect\u00e9s.<\/p><p>De plus, ces fournisseurs de services nous offrent des garanties suffisantes quant \u00e0 la mise en \u0153uvre de mesures de protection ad\u00e9quates de vos renseignements personnels trait\u00e9s ou communiqu\u00e9s avant que vos renseignements personnels ne leur soient communiqu\u00e9s. Lorsque nos fournisseurs de services n\u2019ont plus besoin de vos renseignements personnels, nous leur demandons de d\u00e9truire ces donn\u00e9es de mani\u00e8re appropri\u00e9e.<\/p><p>Les renseignements personnels que nous recueillons et conservons demeurent prot\u00e9g\u00e9s et sont h\u00e9berg\u00e9s de mani\u00e8re s\u00e9curitaire sur des serveurs pouvant \u00eatre situ\u00e9s \u00e0 l\u2019ext\u00e9rieur du Qu\u00e9bec, soit au Canada et aux \u00c9tats-Unis.<\/p><p>Nous pouvons \u00e9galement partager, transf\u00e9rer ou communiquer, en stricte conformit\u00e9 avec la pr\u00e9sente Politique, vos renseignements personnels avec des tiers lorsque la loi l\u2019exige ou dans le cadre d\u2019une transaction commerciale visant la vente, le transfert ou la cession, en tout ou en partie, de Z\u00e9ro-C ou de nos actifs. Dans ce cas et advenant la concr\u00e9tisation de la transaction commerciale, nous vous informerons avant que vos renseignements personnels ne soient r\u00e9gis par une autre politique de confidentialit\u00e9.<\/p><p>Nous ne vendons pas, n\u2019\u00e9changeons pas, ni ne communiquons autrement vos renseignements personnels \u00e0 de tierces parties, sous r\u00e9serve des exceptions pr\u00e9vues par la loi.<\/p><h3>Conservation des renseignements personnels<\/h3><p>Sous r\u00e9serve des lois applicables, nous conservons vos renseignements personnels uniquement pour le temps n\u00e9cessaire \u00e0 la r\u00e9alisation des fins pour lesquelles ces renseignements ont \u00e9t\u00e9 recueillis, \u00e0 moins que vous ne consentiez \u00e0 ce que vos renseignements personnels soient utilis\u00e9s ou trait\u00e9s \u00e0 une autre fin. Apr\u00e8s ce d\u00e9lai, vos renseignements personnels seront d\u00e9truits ou anonymis\u00e9s de mani\u00e8re s\u00e9curitaire.<\/p><p>Pour obtenir plus d\u2019information sur les p\u00e9riodes pendant lesquelles vos renseignements personnels sont conserv\u00e9s, veuillez nous contacter comme indiqu\u00e9 \u00e0 la section \u00ab Communiquez avec nous \u00bb.<\/p><h3>Droits \u00e0 l\u2019\u00e9gard des renseignements personnels<\/h3><p>Vous disposez des droits suivants :<\/p><p>Le droit d\u2019\u00eatre inform\u00e9 des renseignements personnels que nous d\u00e9tenons \u00e0 votre sujet et de demander une copie des documents contenant vos renseignements personnels, sous r\u00e9serve des exceptions pr\u00e9vues par la loi applicable;<\/p><p>Le droit de faire rectifier, modifier et mettre \u00e0 jour les renseignements personnels que nous d\u00e9tenons \u00e0 votre sujet s\u2019ils sont incomplets, \u00e9quivoques, p\u00e9rim\u00e9s ou inexacts;<\/p><p>Le droit de retirer ou modifier votre consentement \u00e0 ce que Z\u00e9ro-C recueille, utilise, communique ou conserve vos renseignements personnels en tout temps, sous r\u00e9serve des restrictions l\u00e9gales et contractuelles applicables.<\/p><p>Le droit de nous demander de cesser de diffuser vos renseignements personnels et de d\u00e9sindexer tout lien rattach\u00e9 \u00e0 votre nom qui donne acc\u00e8s \u00e0 ces renseignements si cette diffusion contrevient \u00e0 la loi ou \u00e0 une ordonnance judiciaire;<\/p><p>Le droit de porter plainte aupr\u00e8s de la Commission d\u2019acc\u00e8s \u00e0 l\u2019information, sous r\u00e9serve des conditions pr\u00e9vues par la loi applicable.<\/p><p>Pour exercer l\u2019un ou l\u2019autre de ces droits, veuillez nous contacter comme indiqu\u00e9 \u00e0 la section \u00ab Communiquez avec nous \u00bb.<\/p><h3>Protection des renseignements personnels<\/h3><p>Z\u00e9ro-C a mis en place des mesures de s\u00e9curit\u00e9 physiques, technologiques et organisationnelles visant \u00e0 prot\u00e9ger ad\u00e9quatement la confidentialit\u00e9 et la s\u00e9curit\u00e9 de vos renseignements personnels contre la perte, le vol ou tout acc\u00e8s, divulgation, reproduction, communication, utilisation, modification non autoris\u00e9e. Ces mesures comprennent l\u2019utilisation d\u2019un portocole SSL, un logiciel de surveillance du r\u00e9seau, l\u2019utilisation d\u2019un pare-feu, le contr\u00f4le des acc\u00e8s \u00e0 nos bureaux et \u00e0 nos \u00e9quipements, la mise en place sur notre Site web d\u2019une connexion s\u00e9curis\u00e9e entre votre appareil et notre serveur, la sensibilisation des employ\u00e9s de Z\u00e9ro-C \u00e0 la pr\u00e9sente Politique, l\u2019obtention de leur engagement \u00e0 s\u2019y conformer et \u00e0 respecter le caract\u00e8re confidentiel de vos renseignements personnels ainsi que l\u2019adoption d\u2019une gouvernance visant notamment la conservation et la destruction s\u00e9curitaires de vos renseignements personnels.<\/p><p>De plus, nous limitons l\u2019acc\u00e8s \u00e0 vos renseignements personnels aux membres du personnel qui en ont besoin pour remplir leurs fonctions. Ces personnes ont seulement acc\u00e8s aux renseignements n\u00e9cessaires pour r\u00e9aliser leurs t\u00e2ches.<\/p><p>Malgr\u00e9 l\u2019adoption de telles mesures, nous ne pouvons garantir la s\u00e9curit\u00e9 absolue de vos renseignements personnels. Si vous avez des raisons de croire que vos Renseignements personnels ne sont plus prot\u00e9g\u00e9s, veuillez nous contacter imm\u00e9diatement comme indiqu\u00e9 \u00e0 la section \u00ab Communiquez avec nous \u00bb.<\/p><h3>Limitation de responsabilit\u00e9<\/h3><p>Z\u00e9ro-C s\u2019engage \u00e0 prendre tous les moyens raisonnables afin d\u2019assurer un niveau de confidentialit\u00e9 et de s\u00e9curit\u00e9 des renseignements personnels conforme aux standards technologiques ad\u00e9quats compte tenu de son secteur d\u2019activit\u00e9.<\/p><p>Malgr\u00e9 ce qui pr\u00e9c\u00e8de, vous d\u00e9clarez comprendre et reconna\u00eetre qu\u2019aucun syst\u00e8me informatique n\u2019offre une s\u00e9curit\u00e9 absolue et qu\u2019une part de risque est toujours pr\u00e9sente lorsque l\u2019on transmet des Renseignements personnels sur le r\u00e9seau public qu\u2019est l\u2019internet.<\/p><p>Vous acceptez ainsi que Z\u00e9ro-C ne puisse \u00eatre tenue responsable de toute violation de confidentialit\u00e9, piratage, virus, perte, vol, utilisation abusive ou alt\u00e9ration des Renseignements personnels transmis ou h\u00e9berg\u00e9es sur ses syst\u00e8mes ou ceux d\u2019un tiers. Vous d\u00e9clarez \u00e9galement renoncer \u00e0 toute r\u00e9clamation \u00e0 cet \u00e9gard, sauf en cas de n\u00e9gligence grave ou de faute intentionnelle de la part Z\u00e9ro-C. En cons\u00e9quence, vous acceptez de d\u00e9gager Z\u00e9ro-C et ses dirigeants, administrateurs, personnes li\u00e9es et partenaires commerciaux de toute responsabilit\u00e9 pour tout dommage de quelque nature que ce soit, qu\u2019il soit direct ou indirect, accessoire, sp\u00e9cial ou cons\u00e9cutif en rapport avec l\u2019utilisation de vos Renseignements personnels.<\/p><p>Dans le cas d\u2019une violation de la confidentialit\u00e9 ou de la s\u00e9curit\u00e9 de vos Renseignements personnels qui pr\u00e9sente un risque \u00e9lev\u00e9 pour vos droits et votre libert\u00e9, cette violation vous sera notifi\u00e9e d\u00e8s que possible, et Z\u00e9ro-C prendra les mesures n\u00e9cessaires pour pr\u00e9server la confidentialit\u00e9 et la s\u00e9curit\u00e9 de vos Renseignements personnels.<\/p><h3>T\u00e9moins de connexion<\/h3><p>Nous utilisons des t\u00e9moins de connexion et autres technologies similaires (collectivement, les \u00ab Cookies \u00bb) pour nous aider \u00e0 op\u00e9rer, prot\u00e9ger et optimiser le Site web et les services que nous offrons. Vous pouvez configurer votre navigateur de mani\u00e8re \u00e0 \u00eatre inform\u00e9 de la mise en place de Cookies lors de votre visite du Site web, pour que vous puissiez d\u00e9cider, dans chaque cas, d\u2019accepter ou de refuser l\u2019utilisation de certains ou de tous les Cookies.<\/p><p>Parmi les Cookies que nous collectons via notre Site web, il y a notamment les suivants :<\/p><p>T\u00e9moins strictement n\u00e9cessaires : ces t\u00e9moins sont utiles afin que le Site Web fonctionne normalement et ces derniers ne peuvent \u00eatre d\u00e9sactiv\u00e9s.<br \/>T\u00e9moins de fonctionnalit\u00e9 : ces t\u00e9moins permettent au Site web de m\u00e9moriser les choix que vous faites (comme votre nom d\u2019utilisateur, votre langue pr\u00e9f\u00e9r\u00e9e, etc.) pour vous offrir une exp\u00e9rience personnalis\u00e9e et am\u00e9lior\u00e9e lors de vos futures visites. En cas de d\u00e9sactivation, ces t\u00e9moins feront en sorte que nos fonctionnalit\u00e9s ne seront pas optimales, voire d\u00e9faillantes.<br \/>T\u00e9moins d\u2019analyse : ces t\u00e9moins nous aident \u00e0 analyser et \u00e0 comprendre comment vous utilisez notre Site web, afin d\u2019am\u00e9liorer sa convivialit\u00e9, ses fonctionnalit\u00e9s et ses contenus.<br \/>T\u00e9moins de rendement (exemple : Google Analytics) : Ceux-ci permettent de comptabiliser les visites et les sources de trafic sur notre Site Web. Si ces derniers sont d\u00e9sactiv\u00e9s, nous ne pourrons savoir \u00e0 quel moment vous avez visit\u00e9 notre Site Web. Ces t\u00e9moins sont anonymes.<br \/>T\u00e9moins de ciblage (exemple : Facebook, LinkedIn) : Ils servent \u00e0 regrouper des renseignements sur vos activit\u00e9s sur notre Site et sur d\u2019autres sites afin de dresser un profil de vos int\u00e9r\u00eats. En les d\u00e9sactivant, vous vous soustrayez \u00e0 notre publicit\u00e9 cibl\u00e9e sur d\u2019autres sites Web.<\/p><h3>Mise \u00e0 jour de la pr\u00e9sente Politique<\/h3><p>Nous nous r\u00e9servons le droit de modifier la pr\u00e9sente Politique \u00e0 tout moment conform\u00e9ment \u00e0 la l\u00e9gislation applicable. En cas de modification, nous publierons la version r\u00e9vis\u00e9e de la Politique de confidentialit\u00e9.<\/p><p>Nous vous encourageons \u00e0 consulter la pr\u00e9sente Politique \u00e0 chaque fois que vous acc\u00e9der \u00e0 notre Site Web afin de demeurer au fait des mesures de protection et des pratiques de saine de vos renseignements personnels.<\/p><p>Si vous n\u2019approuvez pas les nouvelles conditions de la Politique de confidentialit\u00e9, nous vous invitons \u00e0 ne plus utiliser notre Site Web et nos services. Si vous choisissez de continuer d\u2019utiliser notre Site Web ou nos services apr\u00e8s l\u2019entr\u00e9e en vigueur de la nouvelle version de notre Politique, votre utilisation de notre Site Web et nos services sera alors r\u00e9gie par cette nouvelle version de la Politique.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 La protection de la vie priv\u00e9e est importante pour Z\u00e9ro-C. Pour cette raison, nous avons mis en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-5203","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 | Zero-C<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zero-c.com\/fr\/politique-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 | Zero-C\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 La protection de la vie priv\u00e9e est importante pour Z\u00e9ro-C. Pour cette raison, nous avons mis en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zero-c.com\/fr\/politique-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Zero-C\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T01:01:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zero-c.com\\\/fr\\\/politique-confidentialite\\\/\",\"url\":\"https:\\\/\\\/zero-c.com\\\/fr\\\/politique-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 | Zero-C\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeroc.tempurl.host\\\/#website\"},\"datePublished\":\"2025-08-14T13:43:16+00:00\",\"dateModified\":\"2026-03-03T01:01:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zero-c.com\\\/fr\\\/politique-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zero-c.com\\\/fr\\\/politique-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zero-c.com\\\/fr\\\/politique-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zero-c.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zeroc.tempurl.host\\\/#website\",\"url\":\"https:\\\/\\\/zeroc.tempurl.host\\\/\",\"name\":\"Zero C\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zeroc.tempurl.host\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zeroc.tempurl.host\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zeroc.tempurl.host\\\/#organization\",\"name\":\"Zero C\",\"url\":\"https:\\\/\\\/zeroc.tempurl.host\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/zeroc.tempurl.host\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zero-c.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/zero-c.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-1.svg\",\"caption\":\"Zero C\"},\"image\":{\"@id\":\"https:\\\/\\\/zeroc.tempurl.host\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 | Zero-C","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zero-c.com\/fr\/politique-confidentialite\/","og_locale":"fr_CA","og_type":"article","og_title":"Politique de confidentialit\u00e9 | Zero-C","og_description":"Politique de confidentialit\u00e9 La protection de la vie priv\u00e9e est importante pour Z\u00e9ro-C. Pour cette raison, nous avons mis en [&hellip;]","og_url":"https:\/\/zero-c.com\/fr\/politique-confidentialite\/","og_site_name":"Zero-C","article_modified_time":"2026-03-03T01:01:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zero-c.com\/fr\/politique-confidentialite\/","url":"https:\/\/zero-c.com\/fr\/politique-confidentialite\/","name":"Politique de confidentialit\u00e9 | Zero-C","isPartOf":{"@id":"https:\/\/zeroc.tempurl.host\/#website"},"datePublished":"2025-08-14T13:43:16+00:00","dateModified":"2026-03-03T01:01:03+00:00","breadcrumb":{"@id":"https:\/\/zero-c.com\/fr\/politique-confidentialite\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zero-c.com\/fr\/politique-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zero-c.com\/fr\/politique-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zero-c.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/zeroc.tempurl.host\/#website","url":"https:\/\/zeroc.tempurl.host\/","name":"Zero C","description":"","publisher":{"@id":"https:\/\/zeroc.tempurl.host\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zeroc.tempurl.host\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/zeroc.tempurl.host\/#organization","name":"Zero C","url":"https:\/\/zeroc.tempurl.host\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/zeroc.tempurl.host\/#\/schema\/logo\/image\/","url":"https:\/\/zero-c.com\/wp-content\/uploads\/2025\/08\/logo-1.svg","contentUrl":"https:\/\/zero-c.com\/wp-content\/uploads\/2025\/08\/logo-1.svg","caption":"Zero C"},"image":{"@id":"https:\/\/zeroc.tempurl.host\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zero-c.com\/fr\/wp-json\/wp\/v2\/pages\/5203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zero-c.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zero-c.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zero-c.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zero-c.com\/fr\/wp-json\/wp\/v2\/comments?post=5203"}],"version-history":[{"count":0,"href":"https:\/\/zero-c.com\/fr\/wp-json\/wp\/v2\/pages\/5203\/revisions"}],"wp:attachment":[{"href":"https:\/\/zero-c.com\/fr\/wp-json\/wp\/v2\/media?parent=5203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}